{"id":9136,"date":"2025-10-08T08:38:54","date_gmt":"2025-10-08T08:38:54","guid":{"rendered":"https:\/\/canserrat.org\/?p=9136"},"modified":"2026-07-06T12:39:43","modified_gmt":"2026-07-06T12:39:43","slug":"manuela-alarcon-lopez","status":"publish","type":"post","link":"https:\/\/canserrat.org\/es\/manuela-alarcon-lopez","title":{"rendered":"Manuela Alarc\u00f3n L\u00f3pez"},"content":{"rendered":"<img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-9137 aligncenter\" src=\"http:\/\/canserrat.org\/wp-content\/uploads\/2025\/10\/Manuela-Alarcon-BN-manuela-alarcon-247x300.jpg\" alt=\"\" width=\"247\" height=\"300\" srcset=\"https:\/\/canserrat.org\/wp-content\/uploads\/2025\/10\/Manuela-Alarcon-BN-manuela-alarcon-247x300.jpg 247w, https:\/\/canserrat.org\/wp-content\/uploads\/2025\/10\/Manuela-Alarcon-BN-manuela-alarcon-842x1024.jpg 842w, https:\/\/canserrat.org\/wp-content\/uploads\/2025\/10\/Manuela-Alarcon-BN-manuela-alarcon-1263x1536.jpg 1263w, https:\/\/canserrat.org\/wp-content\/uploads\/2025\/10\/Manuela-Alarcon-BN-manuela-alarcon-1684x2048.jpg 1684w, https:\/\/canserrat.org\/wp-content\/uploads\/2025\/10\/Manuela-Alarcon-BN-manuela-alarcon-scaled-658x800.jpg 658w, https:\/\/canserrat.org\/wp-content\/uploads\/2025\/10\/Manuela-Alarcon-BN-manuela-alarcon-scaled-329x400.jpg 329w, https:\/\/canserrat.org\/wp-content\/uploads\/2025\/10\/Manuela-Alarcon-BN-manuela-alarcon-scaled.jpg 2105w\" sizes=\"(max-width: 247px) 100vw, 247px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Manuela Alarc\u00f3n es ceramista radicada en Medell\u00edn (Colombia). Su trabajo gira en torno a la experimentaci\u00f3n con los oficios del barro y a la creaci\u00f3n de piezas y artefactos desde una exploraci\u00f3n formal, pol\u00edtica y ecol\u00f3gica de sus contextos sociales. Manuela estudi\u00f3 Dise\u00f1o Industrial en Colombia y tiene una maestr\u00eda en Teor\u00eda del Arte por la Universidad Duisburg-Essen (Alemania). Ha sido investigadora en cultura material en la Universidad Pontificia Bolivariana de Medell\u00edn, coordinadora de diversas exposiciones de arte contempor\u00e1neo en Colombia, directora de educaci\u00f3n del Museo de Arte Moderno de Medell\u00edn y ha realizado residencias en distintos lugares del pa\u00eds.<\/p>\n<p>Las relaciones entre el dise\u00f1o, la arquitectura y la artesan\u00eda han sido una constante en su trabajo como investigadora y creadora, y la cer\u00e1mica le ha permitido transitar estos espacios para abordar cuestiones sociales, pol\u00edticas e hist\u00f3ricas complejas. En su pr\u00e1ctica actual explora los oficios del barro y su contexto social en diferentes regiones de Colombia y, a partir de la interpretaci\u00f3n de esta experiencia, desarrolla un trabajo con materiales locales.<\/p>\n<p>En sus piezas, el humor, la historia, el trabajo artesanal y la cultura material colombiana juegan un papel determinante en la creaci\u00f3n de objetos que dialogan con la alfarer\u00eda tradicional y con la observaci\u00f3n e imitaci\u00f3n de la naturaleza.<\/p>\n<p>Manuela Alarc\u00f3n estar\u00e1 en residencia en Can Serrat en octubre de 2025.<\/p>\n<div class=\"gmail_default\"><span data-originalfontsize=\"14px\" data-originalcomputedfontsize=\"14\">Sobre su proceso de trabajo en la residencia &gt;&gt;&gt;<\/span><\/div>\n<div><iframe src=\"\/\/docs.google.com\/viewer?url=http%3A%2F%2Fcanserrat.org%2Fwp-content%2Fuploads%2F2025%2F10%2FALARCON_MANUELA_CHECKPOINT_2025-manuela-alarcon.pdf&hl=es&embedded=true\" class=\"gde-frame\" style=\"width:100%; height:500px; border: none;\" scrolling=\"no\"><\/iframe>\n<p class=\"gde-text\"><a href=\"http:\/\/canserrat.org\/wp-content\/uploads\/2025\/10\/ALARCON_MANUELA_CHECKPOINT_2025-manuela-alarcon.pdf\" class=\"gde-link\">Descargar (PDF, 248KB)<\/a><\/p><\/div>\n<div class=\"gmail_default\"><\/div>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Manuela Alarc\u00f3n es ceramista radicada en Medell\u00edn (Colombia). Su trabajo gira en torno a la experimentaci\u00f3n con los oficios del barro y a la creaci\u00f3n de piezas y artefactos desde una exploraci\u00f3n formal, pol\u00edtica y ecol\u00f3gica de sus contextos &hellip; <a href=\"https:\/\/canserrat.org\/es\/manuela-alarcon-lopez\">Continuar<\/a><\/p>\n","protected":false},"author":4,"featured_media":9137,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[22,10,11],"tags":[],"_links":{"self":[{"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/posts\/9136"}],"collection":[{"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/comments?post=9136"}],"version-history":[{"count":2,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/posts\/9136\/revisions"}],"predecessor-version":[{"id":9953,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/posts\/9136\/revisions\/9953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/media\/9137"}],"wp:attachment":[{"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/media?parent=9136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/categories?post=9136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/tags?post=9136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}