{"id":8310,"date":"2024-08-08T10:10:47","date_gmt":"2024-08-08T10:10:47","guid":{"rendered":"https:\/\/canserrat.org\/?p=8310"},"modified":"2024-10-07T09:17:28","modified_gmt":"2024-10-07T09:17:28","slug":"sofia-leibovich","status":"publish","type":"post","link":"https:\/\/canserrat.org\/es\/sofia-leibovich","title":{"rendered":"Sof\u00eda Leibovich"},"content":{"rendered":"<img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-8311 aligncenter\" src=\"http:\/\/canserrat.org\/wp-content\/uploads\/2024\/08\/LEIBOVICH-SOFIA_1-Sofia-Leibovich-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/canserrat.org\/wp-content\/uploads\/2024\/08\/LEIBOVICH-SOFIA_1-Sofia-Leibovich-200x300.jpg 200w, https:\/\/canserrat.org\/wp-content\/uploads\/2024\/08\/LEIBOVICH-SOFIA_1-Sofia-Leibovich-683x1024.jpg 683w, https:\/\/canserrat.org\/wp-content\/uploads\/2024\/08\/LEIBOVICH-SOFIA_1-Sofia-Leibovich-1024x1536.jpg 1024w, https:\/\/canserrat.org\/wp-content\/uploads\/2024\/08\/LEIBOVICH-SOFIA_1-Sofia-Leibovich-1366x2048.jpg 1366w, https:\/\/canserrat.org\/wp-content\/uploads\/2024\/08\/LEIBOVICH-SOFIA_1-Sofia-Leibovich-534x800.jpg 534w, https:\/\/canserrat.org\/wp-content\/uploads\/2024\/08\/LEIBOVICH-SOFIA_1-Sofia-Leibovich-267x400.jpg 267w, https:\/\/canserrat.org\/wp-content\/uploads\/2024\/08\/LEIBOVICH-SOFIA_1-Sofia-Leibovich.jpg 1575w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Sof\u00eda Leibovich es una poeta, escritora y traductora de Buenos Aires, Argentina. Tiene una licenciatura en Artes de la Escritura y un posgrado en Artes del Libro por la Universidad Nacional de las Artes. Fue una de las poetas seleccionadas para participar en la Bienal de Arte Joven de Buenos Aires en 2019. Actualmente est\u00e1 trabajando en su primera novela y en una colecci\u00f3n de poes\u00eda en prosa.<\/p>\n<p>Sof\u00eda realiza su residencia en Can Serrat durante agosto de 2024.","protected":false},"excerpt":{"rendered":"<p>&nbsp; Sof\u00eda Leibovich es una poeta, escritora y traductora de Buenos Aires, Argentina. Tiene una licenciatura en Artes de la Escritura y un posgrado en Artes del Libro por la Universidad Nacional de las Artes. Fue una de las poetas &hellip; <a href=\"https:\/\/canserrat.org\/es\/sofia-leibovich\">Continuar<\/a><\/p>\n","protected":false},"author":4,"featured_media":8311,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[22,10,11],"tags":[],"_links":{"self":[{"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/posts\/8310"}],"collection":[{"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/comments?post=8310"}],"version-history":[{"count":1,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/posts\/8310\/revisions"}],"predecessor-version":[{"id":8312,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/posts\/8310\/revisions\/8312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/media\/8311"}],"wp:attachment":[{"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/media?parent=8310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/categories?post=8310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/tags?post=8310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}