{"id":8304,"date":"2024-08-08T10:01:38","date_gmt":"2024-08-08T10:01:38","guid":{"rendered":"https:\/\/canserrat.org\/?p=8304"},"modified":"2024-10-07T09:18:23","modified_gmt":"2024-10-07T09:18:23","slug":"emilia-perez","status":"publish","type":"post","link":"https:\/\/canserrat.org\/es\/emilia-perez","title":{"rendered":"Emilia P\u00e9rez"},"content":{"rendered":"<img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-8305 aligncenter\" src=\"http:\/\/canserrat.org\/wp-content\/uploads\/2024\/08\/foto-cv-Emilia-Perez-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/canserrat.org\/wp-content\/uploads\/2024\/08\/foto-cv-Emilia-Perez-225x300.jpg 225w, https:\/\/canserrat.org\/wp-content\/uploads\/2024\/08\/foto-cv-Emilia-Perez-768x1024.jpg 768w, https:\/\/canserrat.org\/wp-content\/uploads\/2024\/08\/foto-cv-Emilia-Perez-1152x1536.jpg 1152w, https:\/\/canserrat.org\/wp-content\/uploads\/2024\/08\/foto-cv-Emilia-Perez-1536x2048.jpg 1536w, https:\/\/canserrat.org\/wp-content\/uploads\/2024\/08\/foto-cv-Emilia-Perez-scaled.jpg 1920w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Emilia P\u00e9rez es una traductora, poeta y editora espa\u00f1ola. Ha tomado talleres de escritura creativa desde 2014, lo que la llev\u00f3 a ser una de los diez miembros cofundadores de Perfeito Ediciones, una editorial de poes\u00eda colectiva de Rosario, Argentina. Gracias a Perfeito, public\u00f3 su primer libro de poes\u00eda, <em>Vainilla y coco<\/em>, en 2021.<\/p>\n<p>Ha participado en dos residencias internacionales: una de poes\u00eda (durante el 26\u00ba Festival Internacional de Poes\u00eda de Rosario) y otra de traducci\u00f3n literaria (en la Autumn School of Literary Translation en Buenos Aires).<\/p>\n<p>Trabajando como ling\u00fcista (traduciendo, editando, corrigiendo textos, impartiendo talleres de escritura) y participando en eventos culturales literarios y musicales (tanto ayudando a organizarlos como protagoniz\u00e1ndolos), se considera una defensora de las palabras.\u00a0Disfruta de la naturaleza, la comida, la m\u00fasica y las conversaciones de coraz\u00f3n a coraz\u00f3n.<\/p>\n<p>Emilia realiza su residencia en Can Serrat durante agosto de 2024.","protected":false},"excerpt":{"rendered":"<p>&nbsp; Emilia P\u00e9rez es una traductora, poeta y editora espa\u00f1ola. Ha tomado talleres de escritura creativa desde 2014, lo que la llev\u00f3 a ser una de los diez miembros cofundadores de Perfeito Ediciones, una editorial de poes\u00eda colectiva de Rosario, &hellip; <a href=\"https:\/\/canserrat.org\/es\/emilia-perez\">Continuar<\/a><\/p>\n","protected":false},"author":4,"featured_media":8305,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[22,10,11],"tags":[],"_links":{"self":[{"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/posts\/8304"}],"collection":[{"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/comments?post=8304"}],"version-history":[{"count":2,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/posts\/8304\/revisions"}],"predecessor-version":[{"id":8334,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/posts\/8304\/revisions\/8334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/media\/8305"}],"wp:attachment":[{"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/media?parent=8304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/categories?post=8304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/tags?post=8304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}