{"id":4479,"date":"2020-01-08T17:01:56","date_gmt":"2020-01-08T17:01:56","guid":{"rendered":"http:\/\/canserrat.org\/?p=4479"},"modified":"2020-01-31T13:56:34","modified_gmt":"2020-01-31T13:56:34","slug":"martha-luisa-hernandez-cadenas","status":"publish","type":"post","link":"https:\/\/canserrat.org\/es\/martha-luisa-hernandez-cadenas","title":{"rendered":"Martha Luisa Herna\u0301ndez Cadenas"},"content":{"rendered":"<span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Martha Luisa Herna\u0301ndez Cadenas | Martica Minipunto. Teatro\u0301loga, poeta y performer. Lo u\u0301nico que le interesa es la experiencia de conocer al otro. Su obra se sucede en los bordes y la imposibilidad de esa experiencia.\\nHa publicado el poemario Di\u0301as de hormigas (Ediciones Unio\u0301n, 2018) con el que obtuviera el Premio David de Poesi\u0301a 2017. Ganadora del Premio de ensayo La Selva Oscura por su investigacio\u0301n Notas de un simulador. La cri\u0301tica teatral de Calvert Casey (1960-1965). Ganadora del Premio de Teatrologi\u0301a Rine Leal por su libro ESTA OBRA HABLA DE TI Y DE MI. Ensayos para (des)a(r)mar la experimentacio\u0301n esce\u0301nica en Cuba (2012-2018). &quot;}\" data-sheets-userformat=\"{&quot;2&quot;:513,&quot;3&quot;:{&quot;1&quot;:0},&quot;12&quot;:0}\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-4480 aligncenter\" src=\"http:\/\/canserrat.org\/wp-content\/uploads\/2020\/01\/martha-300x189.jpg\" alt=\"\" width=\"300\" height=\"189\" srcset=\"https:\/\/canserrat.org\/wp-content\/uploads\/2020\/01\/martha-300x189.jpg 300w, https:\/\/canserrat.org\/wp-content\/uploads\/2020\/01\/martha-1024x645.jpg 1024w, https:\/\/canserrat.org\/wp-content\/uploads\/2020\/01\/martha-80x50.jpg 80w, https:\/\/canserrat.org\/wp-content\/uploads\/2020\/01\/martha-635x400.jpg 635w, https:\/\/canserrat.org\/wp-content\/uploads\/2020\/01\/martha.jpg 1185w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Martha Luisa Herna\u0301ndez Cadenas | Martica Minipunto. Teatro\u0301loga, poeta y performer. Lo u\u0301nico que le interesa es la experiencia de conocer al otro. Su obra se sucede en los bordes y la imposibilidad de esa experiencia.\\nHa publicado el poemario Di\u0301as de hormigas (Ediciones Unio\u0301n, 2018) con el que obtuviera el Premio David de Poesi\u0301a 2017. Ganadora del Premio de ensayo La Selva Oscura por su investigacio\u0301n Notas de un simulador. La cri\u0301tica teatral de Calvert Casey (1960-1965). Ganadora del Premio de Teatrologi\u0301a Rine Leal por su libro ESTA OBRA HABLA DE TI Y DE MI. Ensayos para (des)a(r)mar la experimentacio\u0301n esce\u0301nica en Cuba (2012-2018). &quot;}\" data-sheets-userformat=\"{&quot;2&quot;:513,&quot;3&quot;:{&quot;1&quot;:0},&quot;12&quot;:0}\">Martha Luisa Herna\u0301ndez Cadenas | Martica Minipunto. Teatro\u0301loga, poeta y performer. Lo u\u0301nico que le interesa es la experiencia de conocer al otro. Su obra se sucede en los bordes y la imposibilidad de esa experiencia.<br \/>\nHa publicado el poemario Di\u0301as de hormigas (Ediciones Unio\u0301n, 2018) con el que obtuviera el Premio David de Poesi\u0301a 2017. Ganadora del Premio de ensayo La Selva Oscura por su investigacio\u0301n sobre Notas de un simulador. La cri\u0301tica teatral de Calvert Casey (1960-1965). Ganadora del Premio de Teatrologi\u0301a Rine Leal por su libro ESTA OBRA HABLA DE TI Y DE MI. Ensayos para (des)a(r)mar la experimentacio\u0301n esce\u0301nica en Cuba (2012-2018).<\/span>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Martha Luisa Herna\u0301ndez Cadenas | Martica Minipunto. Teatro\u0301loga, poeta y performer. Lo u\u0301nico que le interesa es la experiencia de conocer al otro. Su obra se sucede en los bordes y la imposibilidad de esa experiencia. Ha publicado el &hellip; <a href=\"https:\/\/canserrat.org\/es\/martha-luisa-hernandez-cadenas\">Continuar<\/a><\/p>\n","protected":false},"author":4,"featured_media":4480,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[10,30,11],"tags":[],"_links":{"self":[{"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/posts\/4479"}],"collection":[{"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/comments?post=4479"}],"version-history":[{"count":2,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/posts\/4479\/revisions"}],"predecessor-version":[{"id":4522,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/posts\/4479\/revisions\/4522"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/media\/4480"}],"wp:attachment":[{"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/media?parent=4479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/categories?post=4479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canserrat.org\/es\/wp-json\/wp\/v2\/tags?post=4479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}